{"id":3989,"date":"2018-10-05T12:08:58","date_gmt":"2018-10-05T17:08:58","guid":{"rendered":"https:\/\/vendiendo.co\/blogs\/?p=3989"},"modified":"2023-03-29T12:12:08","modified_gmt":"2023-03-29T17:12:08","slug":"vendiendo-co-software-pos-actualizacion-3-0-1","status":"publish","type":"post","link":"https:\/\/vendiendo.co\/blogs\/vendiendo-co-software-pos-actualizacion-3-0-1\/","title":{"rendered":"Vendiendo.co Software POS &#8211; Actualizaci\u00f3n 3.0.1"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenidos de la p\u00e1gina<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #aa2727;color:#aa2727\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #aa2727;color:#aa2727\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/vendiendo.co\/blogs\/vendiendo-co-software-pos-actualizacion-3-0-1\/#discriminacion_de_impuestos_iva_e_impoconsumo_en_productos\" >Discriminaci\u00f3n de impuestos IVA e Impoconsumo en productos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/vendiendo.co\/blogs\/vendiendo-co-software-pos-actualizacion-3-0-1\/#discriminacion_de_impuestos_en_importacion_de_productos\" >Discriminaci\u00f3n de impuestos en Importaci\u00f3n de Productos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/vendiendo.co\/blogs\/vendiendo-co-software-pos-actualizacion-3-0-1\/#inclusion_del_impuesto_al_consumo_de_las_bolsas_plasticas_icpb\" >Inclusi\u00f3n del Impuesto al Consumo de las Bolsas Pl\u00e1sticas (ICPB)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/vendiendo.co\/blogs\/vendiendo-co-software-pos-actualizacion-3-0-1\/#discriminacion_de_impuestos_al_facturar\" >Discriminaci\u00f3n de Impuestos al facturar<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/vendiendo.co\/blogs\/vendiendo-co-software-pos-actualizacion-3-0-1\/#discrimacion_de_impuestos_en_los_datos_de_la_factura_pagada\" >Discrimaci\u00f3n de impuestos en los datos de la factura pagada<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/vendiendo.co\/blogs\/vendiendo-co-software-pos-actualizacion-3-0-1\/#discriminacion_de_impuestos_en_la_impresion_de_la_factura_pos\" >Discriminaci\u00f3n de impuestos en la impresi\u00f3n de la factura POS<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/vendiendo.co\/blogs\/vendiendo-co-software-pos-actualizacion-3-0-1\/#discriminacion_de_impuestos_en_la_impresion_a_media_carta\" >Discriminaci\u00f3n de impuestos en la impresi\u00f3n a media carta<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/vendiendo.co\/blogs\/vendiendo-co-software-pos-actualizacion-3-0-1\/#discriminacion_de_iva_impoconsumo_e_icbp_en_los_reportes\" >Discriminaci\u00f3n de IVA, Impoconsumo e ICBP en los reportes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/vendiendo.co\/blogs\/vendiendo-co-software-pos-actualizacion-3-0-1\/#discrimininacion_de_impuestos_en_las_cotizaciones\" >Discrimininaci\u00f3n de Impuestos en las Cotizaciones<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/vendiendo.co\/blogs\/vendiendo-co-software-pos-actualizacion-3-0-1\/#alertas_por_descuentos_aplicados_en_el_sistema\" >Alertas por descuentos aplicados en el sistema<\/a><\/li><\/ul><\/nav><\/div>\n<p>La actualizaci\u00f3n 3.0.1 de Vendiendo.co Sistema POS, incluye nuevas funciones y mejoras para hacer de <a href=\"Vendiendo.co\">Vendiendo.co<\/a> el mejor aliado de tu negocio:<\/p>\n<figure id=\"attachment_3998\" aria-describedby=\"caption-attachment-3998\" style=\"width: 336px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-3998\" src=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Actualizaci\u00f3n-Vendiendo-3.0.1-300x191.png\" alt=\"Actualizaci\u00f3n Vendiendo 3.0.1\" width=\"336\" height=\"214\" srcset=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Actualizaci\u00f3n-Vendiendo-3.0.1-300x191.png 300w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Actualizaci\u00f3n-Vendiendo-3.0.1-502x319.png 502w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Actualizaci\u00f3n-Vendiendo-3.0.1-768x489.png 768w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Actualizaci\u00f3n-Vendiendo-3.0.1-600x382.png 600w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Actualizaci\u00f3n-Vendiendo-3.0.1.png 814w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><figcaption id=\"caption-attachment-3998\" class=\"wp-caption-text\">Actualizaci\u00f3n Vendiendo 3.0.1<\/figcaption><\/figure>\n<p><strong>IMPORTANTE<\/strong>: Para activar completamente esta actualizaci\u00f3n debes limpiar el cach\u00e9 del navegador presionando al mismo tiempo las teclas CTRL + F5.<\/p>\n<p>Te invitamos a leer cada una de las siguientes p\u00e1ginas, donde se describen en detalle los cambios incluidos durante esta actualizaci\u00f3n del sistema:<\/p>\n<hr>\n<h2><span class=\"ez-toc-section\" id=\"discriminacion_de_impuestos_iva_e_impoconsumo_en_productos\"><\/span><strong>Discriminaci\u00f3n de impuestos IVA e Impoconsumo en productos<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr>\n<p>Ahora&nbsp; podr\u00e1s <strong>discriminar<\/strong> en tus productos los impuestos de <strong>IVA<\/strong> e <strong>Impoconsumo<\/strong>&nbsp;de acuerdo a las tarifas vigentes. Esta distinci\u00f3n se realiza durante la creaci\u00f3n manual de un producto, indicando a qu\u00e9 tipo de impuesto (IVA, IMPOC) pertenece la tarifa indicada:<\/p>\n<figure id=\"attachment_3990\" aria-describedby=\"caption-attachment-3990\" style=\"width: 773px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3990 \" src=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Impuestos-Producto-Manual-e1538759308458-300x104.png\" alt=\"Impuestos Producto Manual\" width=\"773\" height=\"268\" srcset=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Impuestos-Producto-Manual-e1538759308458-300x104.png 300w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Impuestos-Producto-Manual-e1538759308458-502x173.png 502w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Impuestos-Producto-Manual-e1538759308458-768x265.png 768w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Impuestos-Producto-Manual-e1538759308458-1024x354.png 1024w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Impuestos-Producto-Manual-e1538759308458.png 1083w\" sizes=\"auto, (max-width: 773px) 100vw, 773px\" \/><figcaption id=\"caption-attachment-3990\" class=\"wp-caption-text\">Impuestos Producto Manual<\/figcaption><\/figure>\n<hr>\n<h2><span class=\"ez-toc-section\" id=\"discriminacion_de_impuestos_en_importacion_de_productos\"><\/span><strong>Discriminaci\u00f3n de impuestos en Importaci\u00f3n de Productos<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr>\n<p>En la <strong>importaci\u00f3n de productos<\/strong>, se cuenta con una nueva columna llamada \u00ab<strong>Tipo Impuesto<\/strong>\u00ab, donde se hace distinci\u00f3n del tipo de impuesto, registrado en la columna iva (tarifa del impuesto):<\/p>\n<figure id=\"attachment_3995\" aria-describedby=\"caption-attachment-3995\" style=\"width: 777px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-3995\" src=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Importacio-de-productos-con-impuestos-300x38.png\" alt=\"Importacio de productos con impuestos\" width=\"777\" height=\"98\" srcset=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Importacio-de-productos-con-impuestos-300x38.png 300w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Importacio-de-productos-con-impuestos-502x63.png 502w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Importacio-de-productos-con-impuestos-768x96.png 768w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Importacio-de-productos-con-impuestos-1024x128.png 1024w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Importacio-de-productos-con-impuestos.png 1136w\" sizes=\"auto, (max-width: 777px) 100vw, 777px\" \/><figcaption id=\"caption-attachment-3995\" class=\"wp-caption-text\">Importacio de productos con impuestos<\/figcaption><\/figure>\n<hr>\n<h2><span class=\"ez-toc-section\" id=\"inclusion_del_impuesto_al_consumo_de_las_bolsas_plasticas_icpb\"><\/span><strong>Inclusi\u00f3n del Impuesto al Consumo de las Bolsas Pl\u00e1sticas (ICPB)<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr>\n<p>Tambi\u00e9n podr\u00e1s incluir el <strong>Impuesto al Consumo de Bolsas Pl\u00e1sticas<\/strong> (ICPB), si est\u00e1s obligado a cobrarlo a tus clientes. Como es un impuesto que se registra para un tipo de producto, que son las bolsas pl\u00e1sticas, \u00e9ste se registra en el m\u00f3dulo de Productos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3991 \" src=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/ICBP-Vendiendo-e1538759442823-300x113.png\" alt=\"ICBP Vendiendo\" width=\"783\" height=\"295\" srcset=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/ICBP-Vendiendo-e1538759442823-300x113.png 300w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/ICBP-Vendiendo-e1538759442823-502x189.png 502w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/ICBP-Vendiendo-e1538759442823-768x289.png 768w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/ICBP-Vendiendo-e1538759442823-1024x385.png 1024w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/ICBP-Vendiendo-e1538759442823.png 1116w\" sizes=\"auto, (max-width: 783px) 100vw, 783px\" \/><\/p>\n<p>Para este impuesto que se cobra en pesos, y no por porcentaje,&nbsp; se introducen los datos del producto bolsa pl\u00e1stica de la siguiente forma:<\/p>\n<p style=\"padding-left: 30px;\">1) El <strong>Precio de Costo<\/strong>, por ejemplo 30, que ser\u00eda el valor en pesos del impuesto a las bolsas pl\u00e1sticas.<\/p>\n<p style=\"padding-left: 30px;\">2) En el campo <strong>Iva% en Compra<\/strong> se pone <strong>100%.<\/strong><\/p>\n<p style=\"padding-left: 30px;\">3) En <strong>Tipo<\/strong> se escoge <strong>icbp<\/strong>.<\/p>\n<p style=\"padding-left: 30px;\">4) Y en <strong>Precio de Venta<\/strong> se pone <strong>0<\/strong>.<\/p>\n<hr>\n<h2><span class=\"ez-toc-section\" id=\"discriminacion_de_impuestos_al_facturar\"><\/span><strong>Discriminaci\u00f3n de Impuestos al facturar<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr>\n<p>Al momento de facturar, en el lado izquierdo del panel de facturaci\u00f3n se pueden ver los impuestos discriminados para la compra actual:<\/p>\n<figure id=\"attachment_4003\" aria-describedby=\"caption-attachment-4003\" style=\"width: 792px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-4003\" src=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-factura-300x137.png\" alt=\"Discriminaci\u00f3n al facturar\" width=\"792\" height=\"362\" srcset=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-factura-300x137.png 300w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-factura-502x230.png 502w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-factura-768x351.png 768w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-factura-1024x468.png 1024w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-factura.png 1321w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><figcaption id=\"caption-attachment-4003\" class=\"wp-caption-text\">Discriminaci\u00f3n al facturar<\/figcaption><\/figure>\n<hr>\n<h2><span class=\"ez-toc-section\" id=\"discrimacion_de_impuestos_en_los_datos_de_la_factura_pagada\"><\/span><strong>Discrimaci\u00f3n de impuestos en los datos de la factura pagada<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr>\n<p>Una vez que la factura fue pagada, en el resumen de la factura se observa la discriminaci\u00f3n de los impuestos:<\/p>\n<figure id=\"attachment_4002\" aria-describedby=\"caption-attachment-4002\" style=\"width: 788px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-4002\" src=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-factura-pagada-300x104.png\" alt=\"Discriminaci\u00f3n en factura pagada\" width=\"788\" height=\"273\" srcset=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-factura-pagada-300x104.png 300w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-factura-pagada-502x174.png 502w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-factura-pagada-768x266.png 768w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-factura-pagada-1024x354.png 1024w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-factura-pagada.png 1309w\" sizes=\"auto, (max-width: 788px) 100vw, 788px\" \/><figcaption id=\"caption-attachment-4002\" class=\"wp-caption-text\">Discriminaci\u00f3n en factura pagada<\/figcaption><\/figure>\n<hr>\n<h2><span class=\"ez-toc-section\" id=\"discriminacion_de_impuestos_en_la_impresion_de_la_factura_pos\"><\/span><strong>Discriminaci\u00f3n de impuestos en la impresi\u00f3n de la factura POS<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr>\n<p>En la impresi\u00f3n de la factura en tirilla, se muestra la discriminaci\u00f3n de los impuestos IVA, impoconsumo e impuesto al consumo de bolsas pl\u00e1sticas:<\/p>\n<figure id=\"attachment_4005\" aria-describedby=\"caption-attachment-4005\" style=\"width: 287px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-4005\" src=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-impresi\u00f3n-de-la-factura-POS-132x300.png\" alt=\"Discriminaci\u00f3n en la impresi\u00f3n de la factura POS\" width=\"287\" height=\"652\" srcset=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-impresi\u00f3n-de-la-factura-POS-132x300.png 132w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-impresi\u00f3n-de-la-factura-POS.png 269w\" sizes=\"auto, (max-width: 287px) 100vw, 287px\" \/><figcaption id=\"caption-attachment-4005\" class=\"wp-caption-text\">Discriminaci\u00f3n en la impresi\u00f3n de la factura POS<\/figcaption><\/figure>\n<hr>\n<h2><span class=\"ez-toc-section\" id=\"discriminacion_de_impuestos_en_la_impresion_a_media_carta\"><\/span><strong>Discriminaci\u00f3n de impuestos en la impresi\u00f3n a media carta<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr>\n<p>De igual modo, en la impresi\u00f3n de la factura en media carte, se muestra el discriminado por impuestos pagados por cada producto, como el consolidado final de impuestos por la venta:<\/p>\n<figure id=\"attachment_4004\" aria-describedby=\"caption-attachment-4004\" style=\"width: 567px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-4004\" src=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-impresi\u00f3n-de-la-factura-carta-300x283.png\" alt=\"Discriminaci\u00f3n en la impresi\u00f3n de la factura carta\" width=\"567\" height=\"535\" srcset=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-impresi\u00f3n-de-la-factura-carta-300x283.png 300w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-impresi\u00f3n-de-la-factura-carta.png 473w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><figcaption id=\"caption-attachment-4004\" class=\"wp-caption-text\">Discriminaci\u00f3n en la impresi\u00f3n de la factura carta<\/figcaption><\/figure>\n<hr>\n<h2><span class=\"ez-toc-section\" id=\"discriminacion_de_iva_impoconsumo_e_icbp_en_los_reportes\"><\/span><strong>Discriminaci\u00f3n de IVA, Impoconsumo e ICBP en los reportes<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr>\n<p>En tus <strong>reportes de ventas<\/strong> y facturaci\u00f3n podr\u00e1s ver de manera discriminada los impuestos de <strong>IVA, Impoconsumo e ICBP<\/strong>, por cada una de las facturas, y en el valor totalizado:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3992 \" src=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Reporte-de-Impuestos-e1538759498502-300x129.png\" alt=\"Reporte de Impuestos\" width=\"740\" height=\"318\" srcset=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Reporte-de-Impuestos-e1538759498502-300x129.png 300w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Reporte-de-Impuestos-e1538759498502-502x215.png 502w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Reporte-de-Impuestos-e1538759498502-768x330.png 768w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Reporte-de-Impuestos-e1538759498502.png 932w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/p>\n<hr>\n<h2><span class=\"ez-toc-section\" id=\"discrimininacion_de_impuestos_en_las_cotizaciones\"><\/span><strong>Discrimininaci\u00f3n de Impuestos en las Cotizaciones<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr>\n<p>En la elaboraci\u00f3n de las cotizaciones tambi\u00e9n se est\u00e1 discriminando cada uno de los impuestos. De igual modo cuando se factura la cotizaci\u00f3n, estos valores se transfieren a dicho documento:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4006\" src=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-cotizaci\u00f3n-300x186.png\" alt=\"Discriminaci\u00f3n en la cotizaci\u00f3n\" width=\"771\" height=\"478\" srcset=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-cotizaci\u00f3n-300x186.png 300w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-cotizaci\u00f3n-502x311.png 502w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-cotizaci\u00f3n-768x476.png 768w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-cotizaci\u00f3n.png 940w\" sizes=\"auto, (max-width: 771px) 100vw, 771px\" \/><\/p>\n<p>Igualmente al imprimir la cotizaci\u00f3n se muestra el discriminado de impuestos:<\/p>\n<figure id=\"attachment_4007\" aria-describedby=\"caption-attachment-4007\" style=\"width: 767px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-4007\" src=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-impresi\u00f3n-de-la-cotizaci\u00f3n-300x240.png\" alt=\"Discriminaci\u00f3n en la impresi\u00f3n de la cotizaci\u00f3n\" width=\"767\" height=\"614\" srcset=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-impresi\u00f3n-de-la-cotizaci\u00f3n-300x240.png 300w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Discriminaci\u00f3n-en-la-impresi\u00f3n-de-la-cotizaci\u00f3n.png 459w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/><figcaption id=\"caption-attachment-4007\" class=\"wp-caption-text\">Discriminaci\u00f3n en la impresi\u00f3n de la cotizaci\u00f3n<\/figcaption><\/figure>\n<hr>\n<h2><span class=\"ez-toc-section\" id=\"alertas_por_descuentos_aplicados_en_el_sistema\"><\/span><strong>Alertas por descuentos aplicados en el sistema<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr>\n<p>Cuando est\u00e9s registrando una factura, ahora se te notificar\u00e1 los <strong>descuentos<\/strong> que el sistema est\u00e1 calculando, para evitar errores que se pueden presentar por digitaci\u00f3n.<\/p>\n<figure id=\"attachment_3996\" aria-describedby=\"caption-attachment-3996\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3996 \" src=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Alerta-en-Descuento-e1538760504175-300x160.png\" alt=\"Alerta en Descuentos\" width=\"750\" height=\"400\" srcset=\"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Alerta-en-Descuento-e1538760504175-300x160.png 300w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Alerta-en-Descuento-e1538760504175-502x267.png 502w, https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Alerta-en-Descuento-e1538760504175.png 748w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-3996\" class=\"wp-caption-text\">Alerta en Descuentos<\/figcaption><\/figure>\n<p>Esta actualizaci\u00f3n comenzar\u00e1 a operar desde el d\u00eda 9 de Octubre de 2018 en horas de la noche para todos nuestros clientes.<\/p>\n<p><a href=\"https:\/\/vendiendo.co\">Vendiendo.co<\/a> es tu mejor aliado para controlar y hacer crecer tu negocio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La actualizaci\u00f3n 3.0.1 de Vendiendo.co Sistema POS, incluye nuevas funciones y mejoras para hacer de Vendiendo.co el mejor aliado de tu negocio: IMPORTANTE: Para activar completamente esta actualizaci\u00f3n debes limpiar[&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":3998,"comment_status":"open","ping_status":"closed","sticky":false,"template":"template-centered.php","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1414],"tags":[30],"class_list":["post-3989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sistema-pos","tag-vendiendo-co"],"jetpack_featured_media_url":"https:\/\/vendiendo.co\/blogs\/wp-content\/uploads\/2018\/10\/Actualizaci\u00f3n-Vendiendo-3.0.1.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/vendiendo.co\/blogs\/wp-json\/wp\/v2\/posts\/3989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vendiendo.co\/blogs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendiendo.co\/blogs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendiendo.co\/blogs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vendiendo.co\/blogs\/wp-json\/wp\/v2\/comments?post=3989"}],"version-history":[{"count":0,"href":"https:\/\/vendiendo.co\/blogs\/wp-json\/wp\/v2\/posts\/3989\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vendiendo.co\/blogs\/wp-json\/wp\/v2\/media\/3998"}],"wp:attachment":[{"href":"https:\/\/vendiendo.co\/blogs\/wp-json\/wp\/v2\/media?parent=3989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendiendo.co\/blogs\/wp-json\/wp\/v2\/categories?post=3989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendiendo.co\/blogs\/wp-json\/wp\/v2\/tags?post=3989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}